{"id":4,"count":5,"description":"","link":"https:\/\/navidesign.jp\/ronchan_blog\/category\/projects-shop\/","name":"\u30b7\u30e7\u30c3\u30d7","slug":"projects-shop","taxonomy":"category","parent":0,"meta":[],"_links":{"self":[{"href":"https:\/\/navidesign.jp\/ronchan_blog\/wp-json\/wp\/v2\/categories\/4"}],"collection":[{"href":"https:\/\/navidesign.jp\/ronchan_blog\/wp-json\/wp\/v2\/categories"}],"about":[{"href":"https:\/\/navidesign.jp\/ronchan_blog\/wp-json\/wp\/v2\/taxonomies\/category"}],"wp:post_type":[{"href":"https:\/\/navidesign.jp\/ronchan_blog\/wp-json\/wp\/v2\/posts?categories=4"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}